{"id":9277,"date":"2017-10-30T11:11:21","date_gmt":"2017-10-30T10:11:21","guid":{"rendered":"https:\/\/www.legalife.fr\/guides-juridiques\/?p=9277"},"modified":"2019-11-29T14:43:43","modified_gmt":"2019-11-29T13:43:43","slug":"vos-droits-acheteur-immobilier","status":"publish","type":"post","link":"https:\/\/www.legalife.fr\/guides-juridiques\/vos-droits-acheteur-immobilier\/","title":{"rendered":"Vos droits en tant qu&#8217;acheteur d&#8217;un bien immobilier"},"content":{"rendered":"<p>La maison de vos r\u00eaves enfin acquise, il est temps d&#8217;emm\u00e9nager ! Mais en posant les cartons voil\u00e0 que les mauvaises surprises arrivent &#8230; Quelle est cette \u00e9norme fissure dans le mur que vous n&#8217;aviez pas vu avant ? Et ce voisin qui vous dit qu&#8217;il poss\u00e8de une servitude de passage sur votre propri\u00e9t\u00e9 ?<\/p>\n<p>Nous avons fait le point pour vous sur vos droits en tant qu&#8217;acheteur d&#8217;un bien immobilier.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/d1mxkq1wocxjoy.cloudfront.net\/guides-uploads\/2017\/10\/26095448\/AMETHYSTE-CONTEMPORAINE.jpg\"><img loading=\"lazy\" class=\"alignnone size-large wp-image-9309\" src=\"https:\/\/d1mxkq1wocxjoy.cloudfront.net\/guides-uploads\/2017\/10\/26095448\/AMETHYSTE-CONTEMPORAINE-1024x614.jpg\" alt=\"\" width=\"810\" height=\"486\" srcset=\"https:\/\/d1mxkq1wocxjoy.cloudfront.net\/guides-uploads\/2017\/10\/26095448\/AMETHYSTE-CONTEMPORAINE-1024x614.jpg 1024w, https:\/\/d1mxkq1wocxjoy.cloudfront.net\/guides-uploads\/2017\/10\/26095448\/AMETHYSTE-CONTEMPORAINE-300x180.jpg 300w, https:\/\/d1mxkq1wocxjoy.cloudfront.net\/guides-uploads\/2017\/10\/26095448\/AMETHYSTE-CONTEMPORAINE-768x461.jpg 768w, https:\/\/d1mxkq1wocxjoy.cloudfront.net\/guides-uploads\/2017\/10\/26095448\/AMETHYSTE-CONTEMPORAINE-810x486.jpg 810w, https:\/\/d1mxkq1wocxjoy.cloudfront.net\/guides-uploads\/2017\/10\/26095448\/AMETHYSTE-CONTEMPORAINE-1140x684.jpg 1140w\" sizes=\"(max-width: 810px) 100vw, 810px\" \/><\/a><\/p>\n<p>Le l\u00e9gislateur\u00a0met \u00e0 la charge du vendeur deux obligations qui vous donnent une certaine s\u00e9curit\u00e9 en tant qu&#8217;acheteur d&#8217;une maison ou d&#8217;un appartement : une obligation de <strong>d\u00e9livrance<\/strong> du bien et une obligation de <strong>garantie<\/strong> de ce dernier.<\/p>\n<div id=\"toc_container\" class=\"no_bullets\"><p class=\"toc_title\">Table des mati&egrave;res<\/p><ul class=\"toc_list\"><li><a href=\"#L8217obligation_de_delivrance_du_vendeur\"><span class=\"toc_number toc_depth_1\">1<\/span> L&#8217;obligation de d\u00e9livrance du vendeur<\/a><ul><li><a href=\"#Definition_de_l8217obligation_de_delivrance\"><span class=\"toc_number toc_depth_2\">1.1<\/span> D\u00e9finition de l&#8217;obligation de d\u00e9livrance<\/a><\/li><li><a href=\"#Sanctions_du_vendeur\"><span class=\"toc_number toc_depth_2\">1.2<\/span> Sanctions du vendeur<\/a><\/li><\/ul><\/li><li><a href=\"#L8217obligation_de_garantie\"><span class=\"toc_number toc_depth_1\">2<\/span> L&#8217;obligation de garantie<\/a><ul><li><a href=\"#La_garantie_d8217eviction\"><span class=\"toc_number toc_depth_2\">2.1<\/span> La garantie d&#8217;\u00e9viction<\/a><ul><li><a href=\"#Les_troubles_du_fait_du_vendeur\"><span class=\"toc_number toc_depth_3\">2.1.1<\/span> Les troubles du fait du vendeur<\/a><\/li><li><a href=\"#Les_trouble_d8217un_tiers\"><span class=\"toc_number toc_depth_3\">2.1.2<\/span> Les trouble d&#8217;un tiers<\/a><\/li><\/ul><\/li><li><a href=\"#Sanctions\"><span class=\"toc_number toc_depth_2\">2.2<\/span> Sanctions<\/a><\/li><li><a href=\"#La_garantie_des_vices_caches\"><span class=\"toc_number toc_depth_2\">2.3<\/span> La garantie des vices cach\u00e9s<\/a><ul><li><a href=\"#Conditions_pour_faire_jouer_la_garantie_des_vices_caches\"><span class=\"toc_number toc_depth_3\">2.3.1<\/span> Conditions pour faire jouer la garantie des vices cach\u00e9s<\/a><\/li><li><a href=\"#Mise_en_oeuvre_de_la_garantie_des_vices_caches\"><span class=\"toc_number toc_depth_3\">2.3.2<\/span> Mise en oeuvre de la garantie des vices cach\u00e9s<\/a><\/li><li><a href=\"#La_bonne_ou_mauvaise_foi_du_vendeur\"><span class=\"toc_number toc_depth_3\">2.3.3<\/span> La bonne ou mauvaise foi du vendeur<\/a><\/li><\/ul><\/li><\/ul><\/li><\/ul><\/div>\n<h2><span id=\"L8217obligation_de_delivrance_du_vendeur\">L&#8217;obligation de d\u00e9livrance du vendeur<\/span><\/h2>\n<h3><span id=\"Definition_de_l8217obligation_de_delivrance\">D\u00e9finition de l&#8217;obligation de d\u00e9livrance<\/span><\/h3>\n<p>La principale obligation du vendeur est bien entendu de vous livrer le bien au jour de la signature du contrat de vente (ou \u00e0 une date ult\u00e9rieure \u00e0 condition qu&#8217;une clause ait \u00e9t\u00e9 pr\u00e9vue \u00e0 ce sujet). Le bien doit imp\u00e9rativement vous \u00eatre remis dans le m\u00eame \u00e9tat que le jour de la visite.<\/p>\n<p>Ce bien achet\u00e9 peut \u00eatre libre ou lou\u00e9, ainsi :<\/p>\n<ul>\n<li>s&#8217;il est <strong>libre<\/strong> : le vendeur doit vous donner les clefs et laisser les lieux libres afin que vous puissiez y emm\u00e9nager.<\/li>\n<li>s&#8217;il est <strong>lou\u00e9<\/strong> : le vendeur doit vous donner le contrat de bail, un \u00e9tat des lieux, d\u00e9p\u00f4t de garantie, etc.<\/li>\n<\/ul>\n<p>Le vendeur doit\u00a0vous d\u00e9livrer un bien en conformit\u00e9 avec les sp\u00e9cifications contenues dans le contrat. Cette obligation vous garantit d&#8217;avoir un bien qui correspond \u00e0 celui attendu et qui est apte \u00e0 l&#8217;usage auquel\u00a0vous le destinez.<\/p>\n<h3><span id=\"Sanctions_du_vendeur\">Sanctions du vendeur<\/span><\/h3>\n<p>Si cette obligation de d\u00e9livrance n&#8217;est pas respect\u00e9e par le vendeur, il peut voir sa responsabilit\u00e9 engag\u00e9e.\u00a0Il vous faut saisir le juge et pour cela deux types d&#8217;actions s&#8217;offrent \u00e0 vous, chacune ayant une finalit\u00e9 diff\u00e9rente :<\/p>\n<ul>\n<li>une <strong>annulation de la vente.\u00a0<\/strong>Dans ce cas, le vendeur vous remboursera enti\u00e8rement la somme vers\u00e9e lors de l&#8217;achat et vous serez tenus de lui rendre le bien dans le m\u00eame \u00e9tat qu&#8217;il vous l&#8217;avait transmis.<\/li>\n<li>une <strong>ex\u00e9cution forc\u00e9e du contrat.\u00a0<\/strong> Cela signifie que le juge contraindra le vendeur \u00e0 vous d\u00e9livrer le bien.<\/li>\n<\/ul>\n<p>Il est possible en plus de demander des <strong>dommages &amp; int\u00e9r\u00eats<\/strong> pour le pr\u00e9judice subi\u00a0du fait du d\u00e9faut de d\u00e9livrance.<\/p>\n<h2><span id=\"L8217obligation_de_garantie\">L&#8217;obligation de garantie<\/span><\/h2>\n<h3><span id=\"La_garantie_d8217eviction\">La garantie d&#8217;\u00e9viction<\/span><\/h3>\n<p>Elle vous garantit une possession paisible du bien acquis. Ainsi le vendeur n&#8217;a pas le droit de venir troubler le droit de jouissance de l&#8217;acqu\u00e9reur.<\/p>\n<p>Le trouble peut venir du vendeur mais \u00e9galement d&#8217;un tiers.<\/p>\n<h4><span id=\"Les_troubles_du_fait_du_vendeur\">Les troubles du fait du vendeur<\/span><\/h4>\n<p>Il peut \u00eatre de fait ou de droit :<\/p>\n<ul>\n<li><strong>trouble de fait<\/strong> : lorsque le vendeur vend le m\u00eame bien \u00e0 2 personnes diff\u00e9rentes. Dans ce cas,\u00a0il ne respecte pas l&#8217;obligation de garantie qu&#8217;il a envers le 1er acheteur.<\/li>\n<li><strong>trouble de droit<\/strong> : lorsque le vendeur consid\u00e8re qu&#8217;il est toujours propri\u00e9taire du bien vendu.<\/li>\n<\/ul>\n<h4><span id=\"Les_trouble_d8217un_tiers\">Les trouble d&#8217;un tiers<\/span><\/h4>\n<p>Ce cas se pr\u00e9sente lorsqu&#8217;un tiers au contrat de vente revendique un droit de propri\u00e9t\u00e9 sur le bien vendu.<\/p>\n<h3><span id=\"Sanctions\">Sanctions<\/span><\/h3>\n<p>Ainsi quelque soit le trouble, le vendeur est tenu envers vous, acheteur, de vous restituer le prix du bien vendu ou la somme d&#8217;argent correspondant \u00e0 la partie du bien vendu dont vous \u00eates \u00e9vinc\u00e9.<\/p>\n<h3><span id=\"La_garantie_des_vices_caches\">La garantie des vices cach\u00e9s<\/span><\/h3>\n<p>Un vice est un d\u00e9faut tel qu&#8217;un mur fissur\u00e9, une charpente endommag\u00e9e ou une instabilit\u00e9 de terrain.<\/p>\n<h4><span id=\"Conditions_pour_faire_jouer_la_garantie_des_vices_caches\">Conditions pour faire jouer la garantie des vices cach\u00e9s<\/span><\/h4>\n<p>Pour\u00a0que ce d\u00e9faut soit consid\u00e9r\u00e9 comme un vice cach\u00e9,\u00a0il faut qu&#8217;il r\u00e9ponde \u00e0 4 crit\u00e8res :<\/p>\n<ul>\n<li>le vice doit \u00eatre <strong>inh\u00e9rent \u00e0 la chose.\u00a0<\/strong><\/li>\n<li>le vice doit \u00eatre<strong> cach\u00e9 :\u00a0<\/strong>le vice ne doit pas \u00eatre apparent, ni connu\u00a0par vous-m\u00eame au moment de l&#8217;achat sinon il sera consid\u00e9r\u00e9 que vous achetez le bien en connaissance de cause. Le juge sera amen\u00e9 \u00e0 v\u00e9rifier que ce d\u00e9faut n&#8217;\u00e9tait pas visible pour un acheteur qui effectue des v\u00e9rifications normales de son futur bien.<\/li>\n<li>le vice doit \u00eatre <strong>ant\u00e9rieur \u00e0 la vente :\u00a0<\/strong>\u00e9videmment si le vice est n\u00e9 apr\u00e8s l&#8217;achat, il est impossible de se retourner contre le vendeur.<\/li>\n<li>le vice doit <strong>compromettre l&#8217;usage de la chose :<\/strong> il faut que ce vice emp\u00eache l&#8217;utilisation normale du bien.<\/li>\n<\/ul>\n<h4><span id=\"Mise_en_oeuvre_de_la_garantie_des_vices_caches\">Mise en oeuvre de la garantie des vices cach\u00e9s<\/span><\/h4>\n<p>Vous avez\u00a0un d\u00e9lai de 2 ans pour intenter une action en justice devant le Tribunal de Grande Instance (du lieu du bien immobilier litigieux). Le point de d\u00e9part est le jour de la d\u00e9couverte du d\u00e9faut, et non le jour de l&#8217;achat du bien.<\/p>\n<p>Concernant les types d&#8217;actions, 2 possibilit\u00e9s s&#8217;offrent \u00e0\u00a0vous :<\/p>\n<ul>\n<li><strong>action r\u00e9dhibitoire<\/strong> : faire une demande de remboursement total et rendre le bien. Dans ce cas vous serez int\u00e9gralement rembours\u00e9 par le vendeur et vous lui remettrez le bien immobilier exactement dans le m\u00eame \u00e9tat qu&#8217;il vous l&#8217;a donn\u00e9.<\/li>\n<li><strong>action estimatoire<\/strong> : faire une demande en remboursement partiel et garder le bien immobilier.<\/li>\n<\/ul>\n<p>Il est possible de mettre en place dans le contrat de vente une clause de non-garantie des vices cach\u00e9s qui prot\u00e8ge le vendeur contre toute action en justice de l&#8217;acqu\u00e9reur en cas de d\u00e9couverte d&#8217;un vice cach\u00e9 non connu du vendeur. Evidemment, cette clause ne fonctionne pas s&#8217;il est prouv\u00e9 que le vendeur connaissait le vice et n&#8217;en a pas fait part \u00e0 l&#8217;acqu\u00e9reur.<\/p>\n<h4><span id=\"La_bonne_ou_mauvaise_foi_du_vendeur\">La bonne ou mauvaise foi du vendeur<\/span><\/h4>\n<p>Si vous arrivez \u00e0 prouver que le vendeur est de mauvaise foi, vous pourrez en plus lui demander des dommages et int\u00e9r\u00eats au titre du pr\u00e9judice subi.<\/p>\n<p><span style=\"text-decoration: underline;\">Textes de r\u00e9f\u00e9rence l\u00e9gale :<\/span><\/p>\n<ul>\n<li>l&#8217;obligation de\u00a0d\u00e9livrance :\u00a0<a href=\"https:\/\/www.legifrance.gouv.fr\/affichCodeArticle.do?idArticle=LEGIARTI000006441924&amp;cidTexte=LEGITEXT000006070721\">article 1614 du Code Civil<\/a><\/li>\n<li>la garantie contre les vices cach\u00e9s\u00a0:\u00a0<a href=\"https:\/\/www.legifrance.gouv.fr\/affichCode.do?idSectionTA=LEGISCTA000006165624&amp;cidTexte=LEGITEXT000006070721\">articles 1641 \u00e0 1649 du Code Civil<\/a><\/li>\n<li>la garantie d&#8217;\u00e9viction :<a href=\"https:\/\/www.legifrance.gouv.fr\/affichCode.do;jsessionid=2A838372364869222F30AF38C9312FAC.tplgfr40s_1?idSectionTA=LEGISCTA000006165623&amp;cidTexte=LEGITEXT000006070721&amp;dateTexte=20171020\"> articles 1626 \u00e0 1640 du Code Civil<\/a><\/li>\n<\/ul>\n\n<div class=\"kk-star-ratings\n     kksr-valign-bottom     kksr-align-left    \"\n    data-payload=\"{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;9277&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;count&quot;:&quot;8&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;2.9&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;2.9\\\/5 - (8 votes)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;width&quot;:&quot;81.6&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;}\">\n    \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 81.6px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n    \n<div class=\"kksr-legend\">\n            2.9\/5 - (8 votes)    <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La maison de vos r\u00eaves enfin acquise, il est temps d&#8217;emm\u00e9nager ! Mais en posant les cartons voil\u00e0 que les mauvaises surprises arrivent &#8230; Quelle est cette \u00e9norme fissure dans le mur que vous n&#8217;aviez pas vu avant ? Et ce voisin qui vous dit qu&#8217;il poss\u00e8de une servitude de passage sur votre propri\u00e9t\u00e9 ? [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9351,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[399],"tags":[612,509,611,615,609,613,619,620,621,610,608,618,614,616,617],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Vos droits en tant qu&#039;acheteur d&#039;un bien immobilier - LegaLife<\/title>\n<meta name=\"description\" content=\"Vous venez de trouver la maison ou l&#039;appartement de vos r\u00eaves ! Un achat immobilier est un acte important, quels sont vos droits en tant qu&#039;acheteur ?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.legalife.fr\/guides-juridiques\/vos-droits-acheteur-immobilier\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vos droits en tant qu&#039;acheteur d&#039;un bien immobilier - LegaLife\" \/>\n<meta property=\"og:description\" content=\"Vous venez de trouver la maison ou l&#039;appartement de vos r\u00eaves ! Un achat immobilier est un acte important, quels sont vos droits en tant qu&#039;acheteur ?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.legalife.fr\/guides-juridiques\/vos-droits-acheteur-immobilier\/\" \/>\n<meta property=\"og:site_name\" content=\"LegaLife\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/legalife.fr\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/legalife.fr\" \/>\n<meta property=\"article:published_time\" content=\"2017-10-30T10:11:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-29T13:43:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/d1mxkq1wocxjoy.cloudfront.net\/guides-uploads\/2017\/10\/30111053\/shutterstock_534362170-1024x683.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"LegaLife\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/#organization\",\"name\":\"LegaLife\",\"url\":\"https:\/\/www.legalife.fr\/guides-juridiques\/\",\"sameAs\":[\"https:\/\/instagram.com\/lega_life\/\",\"https:\/\/www.linkedin.com\/company\/legalife\",\"https:\/\/www.pinterest.com\/Legalife_fr\/\",\"https:\/\/www.youtube.com\/channel\/UCB5gtPHHwPuKr7yHnd78f1g\",\"https:\/\/www.facebook.com\/legalife.fr\",\"https:\/\/twitter.com\/legalife\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.legalife.fr\/guides-juridiques\/wp-content\/uploads\/2016\/06\/versionslogo-01.png\",\"contentUrl\":\"https:\/\/www.legalife.fr\/guides-juridiques\/wp-content\/uploads\/2016\/06\/versionslogo-01.png\",\"width\":2292,\"height\":625,\"caption\":\"LegaLife\"},\"image\":{\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/#\/schema\/logo\/image\/\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/#website\",\"url\":\"https:\/\/www.legalife.fr\/guides-juridiques\/\",\"name\":\"LegaLife\",\"description\":\"Toute l&#039;actualit\u00e9 juridique\",\"publisher\":{\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.legalife.fr\/guides-juridiques\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/vos-droits-acheteur-immobilier\/#primaryimage\",\"url\":\"https:\/\/d1mxkq1wocxjoy.cloudfront.net\/guides-uploads\/2017\/10\/30111053\/shutterstock_534362170.jpg\",\"contentUrl\":\"https:\/\/d1mxkq1wocxjoy.cloudfront.net\/guides-uploads\/2017\/10\/30111053\/shutterstock_534362170.jpg\",\"width\":5964,\"height\":3978,\"caption\":\"droits acheteur immobilier\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/vos-droits-acheteur-immobilier\/#webpage\",\"url\":\"https:\/\/www.legalife.fr\/guides-juridiques\/vos-droits-acheteur-immobilier\/\",\"name\":\"Vos droits en tant qu'acheteur d'un bien immobilier - LegaLife\",\"isPartOf\":{\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/vos-droits-acheteur-immobilier\/#primaryimage\"},\"datePublished\":\"2017-10-30T10:11:21+00:00\",\"dateModified\":\"2019-11-29T13:43:43+00:00\",\"description\":\"Vous venez de trouver la maison ou l'appartement de vos r\u00eaves ! Un achat immobilier est un acte important, quels sont vos droits en tant qu'acheteur ?\",\"breadcrumb\":{\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/vos-droits-acheteur-immobilier\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.legalife.fr\/guides-juridiques\/vos-droits-acheteur-immobilier\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/vos-droits-acheteur-immobilier\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Guides juridiques\",\"item\":\"https:\/\/www.legalife.fr\/guides-juridiques\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Immobilier\",\"item\":\"https:\/\/www.legalife.fr\/guides-juridiques\/immobilier\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Vendre ou acheter un bien\",\"item\":\"https:\/\/www.legalife.fr\/guides-juridiques\/immobilier\/vendre-ou-acheter-un-bien\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Vos droits en tant qu&#8217;acheteur d&#8217;un bien immobilier\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/vos-droits-acheteur-immobilier\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/vos-droits-acheteur-immobilier\/#webpage\"},\"author\":{\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/#\/schema\/person\/48a14bcb904db9d47811591521a61112\"},\"headline\":\"Vos droits en tant qu&#8217;acheteur d&#8217;un bien immobilier\",\"datePublished\":\"2017-10-30T10:11:21+00:00\",\"dateModified\":\"2019-11-29T13:43:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/vos-droits-acheteur-immobilier\/#webpage\"},\"wordCount\":996,\"commentCount\":3,\"publisher\":{\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/vos-droits-acheteur-immobilier\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/d1mxkq1wocxjoy.cloudfront.net\/guides-uploads\/2017\/10\/30111053\/shutterstock_534362170.jpg\",\"keywords\":[\"acheter un bien ancien\",\"acheter un bien immobilier\",\"acheter un bien neuf\",\"acheteur\",\"appartement\",\"contrat de vente\",\"d\u00e9livrance du bien\",\"garantie\",\"information\",\"logement\",\"maison\",\"obligations du vendeur\",\"vendeur\",\"vice\",\"vice cach\u00e9\"],\"articleSection\":[\"Vendre ou acheter un bien\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.legalife.fr\/guides-juridiques\/vos-droits-acheteur-immobilier\/#respond\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/#\/schema\/person\/48a14bcb904db9d47811591521a61112\",\"name\":\"LegaLife\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0c59f9bc966559d7cf8640cbb8b89f68?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0c59f9bc966559d7cf8640cbb8b89f68?s=96&d=mm&r=g\",\"caption\":\"LegaLife\"},\"description\":\"LegaLife est un site proposant un accompagnement juridique simple et accessible aux TPE\/PME et aux particuliers. Cette solution permet \u00e0 nos membres de gagner du temps et d'\u00e9conomiser de l'argent face \u00e0 leurs probl\u00e9matiques juridiques.\",\"sameAs\":[\"http:\/\/www.legalife.fr\",\"https:\/\/www.facebook.com\/legalife.fr\",\"https:\/\/www.linkedin.com\/company\/legalife\",\"https:\/\/www.pinterest.com\/Legalife_fr\/\",\"https:\/\/twitter.com\/https:\/\/twitter.com\/legalife\"],\"url\":\"https:\/\/www.legalife.fr\/guides-juridiques\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vos droits en tant qu'acheteur d'un bien immobilier - LegaLife","description":"Vous venez de trouver la maison ou l'appartement de vos r\u00eaves ! Un achat immobilier est un acte important, quels sont vos droits en tant qu'acheteur ?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.legalife.fr\/guides-juridiques\/vos-droits-acheteur-immobilier\/","og_locale":"fr_FR","og_type":"article","og_title":"Vos droits en tant qu'acheteur d'un bien immobilier - LegaLife","og_description":"Vous venez de trouver la maison ou l'appartement de vos r\u00eaves ! Un achat immobilier est un acte important, quels sont vos droits en tant qu'acheteur ?","og_url":"https:\/\/www.legalife.fr\/guides-juridiques\/vos-droits-acheteur-immobilier\/","og_site_name":"LegaLife","article_publisher":"https:\/\/www.facebook.com\/legalife.fr","article_author":"https:\/\/www.facebook.com\/legalife.fr","article_published_time":"2017-10-30T10:11:21+00:00","article_modified_time":"2019-11-29T13:43:43+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/d1mxkq1wocxjoy.cloudfront.net\/guides-uploads\/2017\/10\/30111053\/shutterstock_534362170-1024x683.jpg","type":"image\/jpeg"}],"twitter_misc":{"Written by":"LegaLife","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/www.legalife.fr\/guides-juridiques\/#organization","name":"LegaLife","url":"https:\/\/www.legalife.fr\/guides-juridiques\/","sameAs":["https:\/\/instagram.com\/lega_life\/","https:\/\/www.linkedin.com\/company\/legalife","https:\/\/www.pinterest.com\/Legalife_fr\/","https:\/\/www.youtube.com\/channel\/UCB5gtPHHwPuKr7yHnd78f1g","https:\/\/www.facebook.com\/legalife.fr","https:\/\/twitter.com\/legalife"],"logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.legalife.fr\/guides-juridiques\/#\/schema\/logo\/image\/","url":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-content\/uploads\/2016\/06\/versionslogo-01.png","contentUrl":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-content\/uploads\/2016\/06\/versionslogo-01.png","width":2292,"height":625,"caption":"LegaLife"},"image":{"@id":"https:\/\/www.legalife.fr\/guides-juridiques\/#\/schema\/logo\/image\/"}},{"@type":"WebSite","@id":"https:\/\/www.legalife.fr\/guides-juridiques\/#website","url":"https:\/\/www.legalife.fr\/guides-juridiques\/","name":"LegaLife","description":"Toute l&#039;actualit\u00e9 juridique","publisher":{"@id":"https:\/\/www.legalife.fr\/guides-juridiques\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.legalife.fr\/guides-juridiques\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.legalife.fr\/guides-juridiques\/vos-droits-acheteur-immobilier\/#primaryimage","url":"https:\/\/d1mxkq1wocxjoy.cloudfront.net\/guides-uploads\/2017\/10\/30111053\/shutterstock_534362170.jpg","contentUrl":"https:\/\/d1mxkq1wocxjoy.cloudfront.net\/guides-uploads\/2017\/10\/30111053\/shutterstock_534362170.jpg","width":5964,"height":3978,"caption":"droits acheteur immobilier"},{"@type":"WebPage","@id":"https:\/\/www.legalife.fr\/guides-juridiques\/vos-droits-acheteur-immobilier\/#webpage","url":"https:\/\/www.legalife.fr\/guides-juridiques\/vos-droits-acheteur-immobilier\/","name":"Vos droits en tant qu'acheteur d'un bien immobilier - LegaLife","isPartOf":{"@id":"https:\/\/www.legalife.fr\/guides-juridiques\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.legalife.fr\/guides-juridiques\/vos-droits-acheteur-immobilier\/#primaryimage"},"datePublished":"2017-10-30T10:11:21+00:00","dateModified":"2019-11-29T13:43:43+00:00","description":"Vous venez de trouver la maison ou l'appartement de vos r\u00eaves ! Un achat immobilier est un acte important, quels sont vos droits en tant qu'acheteur ?","breadcrumb":{"@id":"https:\/\/www.legalife.fr\/guides-juridiques\/vos-droits-acheteur-immobilier\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.legalife.fr\/guides-juridiques\/vos-droits-acheteur-immobilier\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.legalife.fr\/guides-juridiques\/vos-droits-acheteur-immobilier\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Guides juridiques","item":"https:\/\/www.legalife.fr\/guides-juridiques\/"},{"@type":"ListItem","position":2,"name":"Immobilier","item":"https:\/\/www.legalife.fr\/guides-juridiques\/immobilier\/"},{"@type":"ListItem","position":3,"name":"Vendre ou acheter un bien","item":"https:\/\/www.legalife.fr\/guides-juridiques\/immobilier\/vendre-ou-acheter-un-bien\/"},{"@type":"ListItem","position":4,"name":"Vos droits en tant qu&#8217;acheteur d&#8217;un bien immobilier"}]},{"@type":"Article","@id":"https:\/\/www.legalife.fr\/guides-juridiques\/vos-droits-acheteur-immobilier\/#article","isPartOf":{"@id":"https:\/\/www.legalife.fr\/guides-juridiques\/vos-droits-acheteur-immobilier\/#webpage"},"author":{"@id":"https:\/\/www.legalife.fr\/guides-juridiques\/#\/schema\/person\/48a14bcb904db9d47811591521a61112"},"headline":"Vos droits en tant qu&#8217;acheteur d&#8217;un bien immobilier","datePublished":"2017-10-30T10:11:21+00:00","dateModified":"2019-11-29T13:43:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.legalife.fr\/guides-juridiques\/vos-droits-acheteur-immobilier\/#webpage"},"wordCount":996,"commentCount":3,"publisher":{"@id":"https:\/\/www.legalife.fr\/guides-juridiques\/#organization"},"image":{"@id":"https:\/\/www.legalife.fr\/guides-juridiques\/vos-droits-acheteur-immobilier\/#primaryimage"},"thumbnailUrl":"https:\/\/d1mxkq1wocxjoy.cloudfront.net\/guides-uploads\/2017\/10\/30111053\/shutterstock_534362170.jpg","keywords":["acheter un bien ancien","acheter un bien immobilier","acheter un bien neuf","acheteur","appartement","contrat de vente","d\u00e9livrance du bien","garantie","information","logement","maison","obligations du vendeur","vendeur","vice","vice cach\u00e9"],"articleSection":["Vendre ou acheter un bien"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.legalife.fr\/guides-juridiques\/vos-droits-acheteur-immobilier\/#respond"]}]},{"@type":"Person","@id":"https:\/\/www.legalife.fr\/guides-juridiques\/#\/schema\/person\/48a14bcb904db9d47811591521a61112","name":"LegaLife","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.legalife.fr\/guides-juridiques\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0c59f9bc966559d7cf8640cbb8b89f68?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0c59f9bc966559d7cf8640cbb8b89f68?s=96&d=mm&r=g","caption":"LegaLife"},"description":"LegaLife est un site proposant un accompagnement juridique simple et accessible aux TPE\/PME et aux particuliers. Cette solution permet \u00e0 nos membres de gagner du temps et d'\u00e9conomiser de l'argent face \u00e0 leurs probl\u00e9matiques juridiques.","sameAs":["http:\/\/www.legalife.fr","https:\/\/www.facebook.com\/legalife.fr","https:\/\/www.linkedin.com\/company\/legalife","https:\/\/www.pinterest.com\/Legalife_fr\/","https:\/\/twitter.com\/https:\/\/twitter.com\/legalife"],"url":"https:\/\/www.legalife.fr\/guides-juridiques\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-json\/wp\/v2\/posts\/9277"}],"collection":[{"href":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-json\/wp\/v2\/comments?post=9277"}],"version-history":[{"count":26,"href":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-json\/wp\/v2\/posts\/9277\/revisions"}],"predecessor-version":[{"id":10561,"href":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-json\/wp\/v2\/posts\/9277\/revisions\/10561"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-json\/wp\/v2\/media\/9351"}],"wp:attachment":[{"href":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-json\/wp\/v2\/media?parent=9277"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-json\/wp\/v2\/categories?post=9277"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-json\/wp\/v2\/tags?post=9277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}