{"id":579,"date":"2014-03-03T20:32:13","date_gmt":"2014-03-03T19:32:13","guid":{"rendered":"http:\/\/www.legalife.fr\/blog\/?p=579"},"modified":"2016-04-20T13:29:02","modified_gmt":"2016-04-20T12:29:02","slug":"elles-ont-redige-leurs-statuts-de-sas-sur-legalife","status":"publish","type":"post","link":"https:\/\/www.legalife.fr\/guides-juridiques\/elles-ont-redige-leurs-statuts-de-sas-sur-legalife\/","title":{"rendered":"Elles ont r\u00e9dig\u00e9 leurs Statuts de SAS sur LegaLife !"},"content":{"rendered":"<p style=\"text-align: justify;\">Alexia et Leslie sont en train de lancer leur soci\u00e9t\u00e9 et elles ont utilis\u00e9 LegaLife pour obtenir leurs <a title=\"Statuts de SAS\" href=\"https:\/\/www.legalife.fr\/document\/statuts-sas\">Statuts de SAS<\/a> personnalis\u00e9s. Nous nous sommes rapproch\u00e9s d\u2019elles afin d\u2019avoir l\u2019avis de deux jeunes entrepreneuses sur leur exp\u00e9rience LegaLife.<\/p>\n<p>Bonjour Alexia et Leslie, merci beaucoup de prendre le temps de r\u00e9pondre \u00e0 nos questions afin de partager votre exp\u00e9rience sur LegaLife \u00e0 nos lecteurs.<\/p>\n<div id=\"toc_container\" class=\"no_bullets\"><p class=\"toc_title\">Table des mati&egrave;res<\/p><ul class=\"toc_list\"><li><a href=\"#Pourquoi_avoir_choisi_LegaLife_pour_la_redaction_de_vos_Statuts_de_SAS\"><span class=\"toc_number toc_depth_1\">1<\/span> Pourquoi avoir choisi LegaLife pour la r\u00e9daction de vos Statuts de SAS ?<\/a><\/li><li><a href=\"#Avez-vous_essaye_d8217obtenir_vos_Statuts_par_dautres_moyens_avant_de_passer_par_LegaLife_Pourquoi_avez-vous_renonce\"><span class=\"toc_number toc_depth_1\">2<\/span> Avez-vous essay\u00e9 d&#8217;obtenir vos Statuts par d\u2019autres moyens avant de passer par LegaLife ? Pourquoi avez-vous renonc\u00e9 ?<\/a><\/li><li><a href=\"#Le_resultat_obtenu_grace_a_LegaLife_vous_convient-il\"><span class=\"toc_number toc_depth_1\">3<\/span> Le r\u00e9sultat obtenu gr\u00e2ce \u00e0 LegaLife vous convient-il ?<\/a><\/li><li><a href=\"#Comment_avez-vous_trouve_lexperience_utilisateur_Avez-vous_ete_suffisamment_guidees_lors_du_questionnaire\"><span class=\"toc_number toc_depth_1\">4<\/span> Comment avez-vous trouv\u00e9 l\u2019exp\u00e9rience utilisateur ? Avez-vous \u00e9t\u00e9 suffisamment guid\u00e9es lors du questionnaire ?<\/a><\/li><li><a href=\"#Avez-vous_fait_appel_a_un_avocat_partenaire_du_site_pour_revoir_vos_Statuts_au_tarif_fixe_de_150_euros_pour_les_Statuts_de_SAS_Pourquoi\"><span class=\"toc_number toc_depth_1\">5<\/span> Avez-vous fait appel \u00e0 un avocat partenaire du site pour revoir vos Statuts au tarif fixe de 150 euros pour les Statuts de SAS ? Pourquoi ?<\/a><\/li><li><a href=\"#Souhaitez-vous_parler_a_nos_lecteurs_de_lentreprise_que_vous_etes_en_train_de_lancer\"><span class=\"toc_number toc_depth_1\">6<\/span> Souhaitez-vous parler \u00e0 nos lecteurs de l\u2019entreprise que vous \u00eates en train de lancer ?<\/a><\/li><\/ul><\/div>\n<h2 style=\"text-align: justify;\"><span id=\"Pourquoi_avoir_choisi_LegaLife_pour_la_redaction_de_vos_Statuts_de_SAS\">Pourquoi avoir choisi LegaLife pour la r\u00e9daction de vos Statuts de SAS ?<\/span><\/h2>\n<p style=\"text-align: justify;\">Nous avons choisi la solution LegaLife car nous sommes deux jeunes entrepreneuses et nous n&#8217;avons pas les moyens de payer un avocat plein pot. La solution nous paraissait simple et rapide mais aussi beaucoup moins ch\u00e8re et tout aussi efficace. En plus les avocats pr\u00e9sents sur le site LegaLife sont \u00e0 notre disposition pour revoir les documents \u00e0 des tarifs forfaitaires si n\u00e9cessaire, cela est tr\u00e8s rassurant.<\/p>\n<h2 style=\"text-align: justify;\"><span id=\"Avez-vous_essaye_d8217obtenir_vos_Statuts_par_dautres_moyens_avant_de_passer_par_LegaLife_Pourquoi_avez-vous_renonce\">Avez-vous essay\u00e9 d&#8217;obtenir vos Statuts par d\u2019autres moyens avant de passer par LegaLife ? Pourquoi avez-vous renonc\u00e9 ?<\/span><\/h2>\n<p style=\"text-align: justify;\">Nous avons commenc\u00e9 par rencontrer un <a href=\"https:\/\/www.legalife.fr\/consulter-un-avocat\">avocat<\/a> mais ses honoraires \u00e9taient beaucoup trop \u00e9lev\u00e9s. Cela ne correspondait pas du tout \u00e0 nos moyens d&#8217;entrepreneuses.<\/p>\n<h2 style=\"text-align: justify;\"><span id=\"Le_resultat_obtenu_grace_a_LegaLife_vous_convient-il\">Le r\u00e9sultat obtenu gr\u00e2ce \u00e0 LegaLife vous convient-il ?<\/span><\/h2>\n<p style=\"text-align: justify;\">Le r\u00e9sultat nous convient parfaitement. Nos <a href=\"https:\/\/www.legalife.fr\/document\/statuts-sas\">statuts de SAS <\/a>ont \u00e9t\u00e9 revus puis enregistr\u00e9s au greffe dans un d\u00e9lais tr\u00e8s court.<\/p>\n<h2 style=\"text-align: justify;\"><span id=\"Comment_avez-vous_trouve_lexperience_utilisateur_Avez-vous_ete_suffisamment_guidees_lors_du_questionnaire\">Comment avez-vous trouv\u00e9 l\u2019exp\u00e9rience utilisateur ? Avez-vous \u00e9t\u00e9 suffisamment guid\u00e9es lors du questionnaire ?<\/span><\/h2>\n<p style=\"text-align: justify;\">Le cheminement vers le document est tr\u00e8s clair, il suffit simplement de r\u00e9pondre aux questions et en quelques minutes on obtient un document personnalis\u00e9 automatiquement. Nous avions quelques modifications \u00e0 faire par la suite ce qui est aussi tr\u00e8s simple car avec notre compte client nous avons pu revenir dessus \u00e0 notre guise.<\/p>\n<h2 style=\"text-align: justify;\"><span id=\"Avez-vous_fait_appel_a_un_avocat_partenaire_du_site_pour_revoir_vos_Statuts_au_tarif_fixe_de_150_euros_pour_les_Statuts_de_SAS_Pourquoi\">Avez-vous fait appel \u00e0 un avocat partenaire du site pour revoir vos Statuts au tarif fixe de 150 euros pour les Statuts de SAS ? Pourquoi ?<\/span><\/h2>\n<p style=\"text-align: justify;\">Nous n&#8217;avons pas eu besoin de <a title=\"Consulter un avocat\" href=\" https:\/\/www.legalife.fr\/consulter-un-avocat\"> consulter un avocat<\/a> pour nos statuts car le document fourni \u00e9tait parfait. Cependant, nous avons choisi de rester abonn\u00e9es au cas ou le besoin se pr\u00e9senterait dans les mois \u00e0 venir.<\/p>\n<h2 style=\"text-align: justify;\"><span id=\"Souhaitez-vous_parler_a_nos_lecteurs_de_lentreprise_que_vous_etes_en_train_de_lancer\">Souhaitez-vous parler \u00e0 nos lecteurs de l\u2019entreprise que vous \u00eates en train de lancer ?<\/span><\/h2>\n<p style=\"text-align: justify;\">Nous avons cr\u00e9\u00e9 une agence de conseil et audit culinaire.<\/p>\n<p><i style=\"text-align: justify;\">Merci beaucoup pour ce retour Alexia et Leslie, nous travaillons pour rendre la r\u00e9daction de vos documents administratifs et juridiques simple, rapide, efficace et moins ch\u00e8re et nous sommes tr\u00e8s heureux que vous ayez \u00e9t\u00e9 satisfaites par votre exp\u00e9rience LegaLife. Tr\u00e8s bon courage pour le lancement de votre soci\u00e9t\u00e9 et \u00e0 bient\u00f4t sur LegaLife.<\/i><br \/>\nSi vous souhaitez cr\u00e9er votre soci\u00e9t\u00e9, LegaLife vous offre<a href=\"https:\/\/www.legalife.fr\/tarifs\"> 7 jours d\u2019essai gratuit et sans engagement<\/a> pour vous accompagner dans toutes vos d\u00e9marches administratives.<\/p>\n<a class=\"mks_button mks_button_large squared\" href=\"https:\/\/www.legalife.fr\/creez-votre-entreprise\" target=\"_self\" style=\"color: #FFFFFF; background-color: #f86b50\" ><i class=\"fa fa-angle-right\"><\/i>Je cr\u00e9e ma soci\u00e9t\u00e9 avec LegaLife<\/a>\n<p>&nbsp;<\/p>\n<p><i><a title=\"LegaLife\" href=\"http:\/\/www.legalife.fr\/blog\/statuts-sas-pacte-dactionnaires-sur-legalife\/\">Charline nous parle aussi de son exp\u00e9rience sur LegaLife<\/a><\/i><\/p>\n\n<div class=\"kk-star-ratings\n     kksr-valign-bottom     kksr-align-left    \"\n    data-payload=\"{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;579&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;count&quot;:&quot;15&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;4.9&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;4.9\\\/5 - (15 votes)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;width&quot;:&quot;139.6&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;}\">\n    \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 139.6px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n    \n<div class=\"kksr-legend\">\n            4.9\/5 - (15 votes)    <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Alexia et Leslie sont en train de lancer leur soci\u00e9t\u00e9 et elles ont utilis\u00e9 LegaLife pour obtenir leurs Statuts de SAS. Nous nous sommes rapproch\u00e9s d\u2019elles afin d\u2019avoir leur avis sur leur exp\u00e9rience LegaLife.<\/p>\n","protected":false},"author":3,"featured_media":610,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[414,258],"tags":[98,40,14,39,41,12,15,11,259],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Elles ont r\u00e9dig\u00e9 leurs Statuts de SAS sur LegaLife ! - LegaLife<\/title>\n<meta name=\"description\" content=\"Alexia et Leslie sont en train de lancer leur soci\u00e9t\u00e9 et elles ont utilis\u00e9 LegaLife pour obtenir leurs Statuts de SAS. Nous nous sommes rapproch\u00e9s d\u2019elles afin d\u2019avoir leur avis sur leur exp\u00e9rience LegaLife.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.legalife.fr\/guides-juridiques\/elles-ont-redige-leurs-statuts-de-sas-sur-legalife\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elles ont r\u00e9dig\u00e9 leurs Statuts de SAS sur LegaLife ! - LegaLife\" \/>\n<meta property=\"og:description\" content=\"Alexia et Leslie sont en train de lancer leur soci\u00e9t\u00e9 et elles ont utilis\u00e9 LegaLife pour obtenir leurs Statuts de SAS. Nous nous sommes rapproch\u00e9s d\u2019elles afin d\u2019avoir leur avis sur leur exp\u00e9rience LegaLife.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.legalife.fr\/guides-juridiques\/elles-ont-redige-leurs-statuts-de-sas-sur-legalife\/\" \/>\n<meta property=\"og:site_name\" content=\"LegaLife\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/legalife.fr\" \/>\n<meta property=\"article:published_time\" content=\"2014-03-03T19:32:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-04-20T12:29:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/d1mxkq1wocxjoy.cloudfront.net\/guides-uploads\/2014\/03\/22230618\/statuts-de-sas_image-a-la-une.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"422\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Thomas Rivoire\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/#organization\",\"name\":\"LegaLife\",\"url\":\"https:\/\/www.legalife.fr\/guides-juridiques\/\",\"sameAs\":[\"https:\/\/instagram.com\/lega_life\/\",\"https:\/\/www.linkedin.com\/company\/legalife\",\"https:\/\/www.pinterest.com\/Legalife_fr\/\",\"https:\/\/www.youtube.com\/channel\/UCB5gtPHHwPuKr7yHnd78f1g\",\"https:\/\/www.facebook.com\/legalife.fr\",\"https:\/\/twitter.com\/legalife\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.legalife.fr\/guides-juridiques\/wp-content\/uploads\/2016\/06\/versionslogo-01.png\",\"contentUrl\":\"https:\/\/www.legalife.fr\/guides-juridiques\/wp-content\/uploads\/2016\/06\/versionslogo-01.png\",\"width\":2292,\"height\":625,\"caption\":\"LegaLife\"},\"image\":{\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/#\/schema\/logo\/image\/\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/#website\",\"url\":\"https:\/\/www.legalife.fr\/guides-juridiques\/\",\"name\":\"LegaLife\",\"description\":\"Toute l&#039;actualit\u00e9 juridique\",\"publisher\":{\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.legalife.fr\/guides-juridiques\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/elles-ont-redige-leurs-statuts-de-sas-sur-legalife\/#primaryimage\",\"url\":\"https:\/\/d1mxkq1wocxjoy.cloudfront.net\/guides-uploads\/2014\/03\/22230618\/statuts-de-sas_image-a-la-une.jpg\",\"contentUrl\":\"https:\/\/d1mxkq1wocxjoy.cloudfront.net\/guides-uploads\/2014\/03\/22230618\/statuts-de-sas_image-a-la-une.jpg\",\"width\":640,\"height\":422,\"caption\":\"Elles ont r\u00e9dig\u00e9 leurs Statuts de SAS sur LegaLife !\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/elles-ont-redige-leurs-statuts-de-sas-sur-legalife\/#webpage\",\"url\":\"https:\/\/www.legalife.fr\/guides-juridiques\/elles-ont-redige-leurs-statuts-de-sas-sur-legalife\/\",\"name\":\"Elles ont r\u00e9dig\u00e9 leurs Statuts de SAS sur LegaLife ! - LegaLife\",\"isPartOf\":{\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/elles-ont-redige-leurs-statuts-de-sas-sur-legalife\/#primaryimage\"},\"datePublished\":\"2014-03-03T19:32:13+00:00\",\"dateModified\":\"2016-04-20T12:29:02+00:00\",\"description\":\"Alexia et Leslie sont en train de lancer leur soci\u00e9t\u00e9 et elles ont utilis\u00e9 LegaLife pour obtenir leurs Statuts de SAS. Nous nous sommes rapproch\u00e9s d\u2019elles afin d\u2019avoir leur avis sur leur exp\u00e9rience LegaLife.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/elles-ont-redige-leurs-statuts-de-sas-sur-legalife\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.legalife.fr\/guides-juridiques\/elles-ont-redige-leurs-statuts-de-sas-sur-legalife\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/elles-ont-redige-leurs-statuts-de-sas-sur-legalife\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Guides juridiques\",\"item\":\"https:\/\/www.legalife.fr\/guides-juridiques\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cr\u00e9ation d'entreprise\",\"item\":\"https:\/\/www.legalife.fr\/guides-juridiques\/creation-entreprise\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Elles ont r\u00e9dig\u00e9 leurs Statuts de SAS sur LegaLife !\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/elles-ont-redige-leurs-statuts-de-sas-sur-legalife\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/elles-ont-redige-leurs-statuts-de-sas-sur-legalife\/#webpage\"},\"author\":{\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/#\/schema\/person\/a8d0c9e67c195e2bb19533e49a8b0c3d\"},\"headline\":\"Elles ont r\u00e9dig\u00e9 leurs Statuts de SAS sur LegaLife !\",\"datePublished\":\"2014-03-03T19:32:13+00:00\",\"dateModified\":\"2016-04-20T12:29:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/elles-ont-redige-leurs-statuts-de-sas-sur-legalife\/#webpage\"},\"wordCount\":524,\"commentCount\":3,\"publisher\":{\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/elles-ont-redige-leurs-statuts-de-sas-sur-legalife\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/d1mxkq1wocxjoy.cloudfront.net\/guides-uploads\/2014\/03\/22230618\/statuts-de-sas_image-a-la-une.jpg\",\"keywords\":[\"cr\u00e9ation d'entreprise\",\"sas\",\"Statut\",\"statuts\",\"statuts d'entreprise\",\"Statuts de SAS\",\"Statuts entreprise\",\"Statuts SAS\",\"t\u00e9moignage\"],\"articleSection\":[\"Les d\u00e9marches pour cr\u00e9er une soci\u00e9t\u00e9\",\"T\u00e9moignages\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.legalife.fr\/guides-juridiques\/elles-ont-redige-leurs-statuts-de-sas-sur-legalife\/#respond\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/#\/schema\/person\/a8d0c9e67c195e2bb19533e49a8b0c3d\",\"name\":\"Thomas Rivoire\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1ba73b56954b9b86c6fd31776e8ad00a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1ba73b56954b9b86c6fd31776e8ad00a?s=96&d=mm&r=g\",\"caption\":\"Thomas Rivoire\"},\"description\":\"Dipl\u00f4m\u00e9 d'HEC Paris et titulaire du dipl\u00f4me sup\u00e9rieur du notariat, j'ai plus de cinq ann\u00e9es d'exp\u00e9rience au sein d'une \u00e9tude de notaires. En tant que co-fondateur de LegaLife, je suis en charge du contenu juridique et du d\u00e9veloppement de l'offre de services que nous proposons \u00e0 nos clients.\",\"sameAs\":[\"https:\/\/fr.linkedin.com\/in\/rivoirethomas\"],\"url\":\"https:\/\/www.legalife.fr\/guides-juridiques\/author\/thomas\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Elles ont r\u00e9dig\u00e9 leurs Statuts de SAS sur LegaLife ! - LegaLife","description":"Alexia et Leslie sont en train de lancer leur soci\u00e9t\u00e9 et elles ont utilis\u00e9 LegaLife pour obtenir leurs Statuts de SAS. Nous nous sommes rapproch\u00e9s d\u2019elles afin d\u2019avoir leur avis sur leur exp\u00e9rience LegaLife.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.legalife.fr\/guides-juridiques\/elles-ont-redige-leurs-statuts-de-sas-sur-legalife\/","og_locale":"fr_FR","og_type":"article","og_title":"Elles ont r\u00e9dig\u00e9 leurs Statuts de SAS sur LegaLife ! - LegaLife","og_description":"Alexia et Leslie sont en train de lancer leur soci\u00e9t\u00e9 et elles ont utilis\u00e9 LegaLife pour obtenir leurs Statuts de SAS. Nous nous sommes rapproch\u00e9s d\u2019elles afin d\u2019avoir leur avis sur leur exp\u00e9rience LegaLife.","og_url":"https:\/\/www.legalife.fr\/guides-juridiques\/elles-ont-redige-leurs-statuts-de-sas-sur-legalife\/","og_site_name":"LegaLife","article_publisher":"https:\/\/www.facebook.com\/legalife.fr","article_published_time":"2014-03-03T19:32:13+00:00","article_modified_time":"2016-04-20T12:29:02+00:00","og_image":[{"width":640,"height":422,"url":"https:\/\/d1mxkq1wocxjoy.cloudfront.net\/guides-uploads\/2014\/03\/22230618\/statuts-de-sas_image-a-la-une.jpg","type":"image\/jpeg"}],"twitter_misc":{"Written by":"Thomas Rivoire","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/www.legalife.fr\/guides-juridiques\/#organization","name":"LegaLife","url":"https:\/\/www.legalife.fr\/guides-juridiques\/","sameAs":["https:\/\/instagram.com\/lega_life\/","https:\/\/www.linkedin.com\/company\/legalife","https:\/\/www.pinterest.com\/Legalife_fr\/","https:\/\/www.youtube.com\/channel\/UCB5gtPHHwPuKr7yHnd78f1g","https:\/\/www.facebook.com\/legalife.fr","https:\/\/twitter.com\/legalife"],"logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.legalife.fr\/guides-juridiques\/#\/schema\/logo\/image\/","url":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-content\/uploads\/2016\/06\/versionslogo-01.png","contentUrl":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-content\/uploads\/2016\/06\/versionslogo-01.png","width":2292,"height":625,"caption":"LegaLife"},"image":{"@id":"https:\/\/www.legalife.fr\/guides-juridiques\/#\/schema\/logo\/image\/"}},{"@type":"WebSite","@id":"https:\/\/www.legalife.fr\/guides-juridiques\/#website","url":"https:\/\/www.legalife.fr\/guides-juridiques\/","name":"LegaLife","description":"Toute l&#039;actualit\u00e9 juridique","publisher":{"@id":"https:\/\/www.legalife.fr\/guides-juridiques\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.legalife.fr\/guides-juridiques\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.legalife.fr\/guides-juridiques\/elles-ont-redige-leurs-statuts-de-sas-sur-legalife\/#primaryimage","url":"https:\/\/d1mxkq1wocxjoy.cloudfront.net\/guides-uploads\/2014\/03\/22230618\/statuts-de-sas_image-a-la-une.jpg","contentUrl":"https:\/\/d1mxkq1wocxjoy.cloudfront.net\/guides-uploads\/2014\/03\/22230618\/statuts-de-sas_image-a-la-une.jpg","width":640,"height":422,"caption":"Elles ont r\u00e9dig\u00e9 leurs Statuts de SAS sur LegaLife !"},{"@type":"WebPage","@id":"https:\/\/www.legalife.fr\/guides-juridiques\/elles-ont-redige-leurs-statuts-de-sas-sur-legalife\/#webpage","url":"https:\/\/www.legalife.fr\/guides-juridiques\/elles-ont-redige-leurs-statuts-de-sas-sur-legalife\/","name":"Elles ont r\u00e9dig\u00e9 leurs Statuts de SAS sur LegaLife ! - LegaLife","isPartOf":{"@id":"https:\/\/www.legalife.fr\/guides-juridiques\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.legalife.fr\/guides-juridiques\/elles-ont-redige-leurs-statuts-de-sas-sur-legalife\/#primaryimage"},"datePublished":"2014-03-03T19:32:13+00:00","dateModified":"2016-04-20T12:29:02+00:00","description":"Alexia et Leslie sont en train de lancer leur soci\u00e9t\u00e9 et elles ont utilis\u00e9 LegaLife pour obtenir leurs Statuts de SAS. Nous nous sommes rapproch\u00e9s d\u2019elles afin d\u2019avoir leur avis sur leur exp\u00e9rience LegaLife.","breadcrumb":{"@id":"https:\/\/www.legalife.fr\/guides-juridiques\/elles-ont-redige-leurs-statuts-de-sas-sur-legalife\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.legalife.fr\/guides-juridiques\/elles-ont-redige-leurs-statuts-de-sas-sur-legalife\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.legalife.fr\/guides-juridiques\/elles-ont-redige-leurs-statuts-de-sas-sur-legalife\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Guides juridiques","item":"https:\/\/www.legalife.fr\/guides-juridiques\/"},{"@type":"ListItem","position":2,"name":"Cr\u00e9ation d'entreprise","item":"https:\/\/www.legalife.fr\/guides-juridiques\/creation-entreprise\/"},{"@type":"ListItem","position":3,"name":"Elles ont r\u00e9dig\u00e9 leurs Statuts de SAS sur LegaLife !"}]},{"@type":"Article","@id":"https:\/\/www.legalife.fr\/guides-juridiques\/elles-ont-redige-leurs-statuts-de-sas-sur-legalife\/#article","isPartOf":{"@id":"https:\/\/www.legalife.fr\/guides-juridiques\/elles-ont-redige-leurs-statuts-de-sas-sur-legalife\/#webpage"},"author":{"@id":"https:\/\/www.legalife.fr\/guides-juridiques\/#\/schema\/person\/a8d0c9e67c195e2bb19533e49a8b0c3d"},"headline":"Elles ont r\u00e9dig\u00e9 leurs Statuts de SAS sur LegaLife !","datePublished":"2014-03-03T19:32:13+00:00","dateModified":"2016-04-20T12:29:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.legalife.fr\/guides-juridiques\/elles-ont-redige-leurs-statuts-de-sas-sur-legalife\/#webpage"},"wordCount":524,"commentCount":3,"publisher":{"@id":"https:\/\/www.legalife.fr\/guides-juridiques\/#organization"},"image":{"@id":"https:\/\/www.legalife.fr\/guides-juridiques\/elles-ont-redige-leurs-statuts-de-sas-sur-legalife\/#primaryimage"},"thumbnailUrl":"https:\/\/d1mxkq1wocxjoy.cloudfront.net\/guides-uploads\/2014\/03\/22230618\/statuts-de-sas_image-a-la-une.jpg","keywords":["cr\u00e9ation d'entreprise","sas","Statut","statuts","statuts d'entreprise","Statuts de SAS","Statuts entreprise","Statuts SAS","t\u00e9moignage"],"articleSection":["Les d\u00e9marches pour cr\u00e9er une soci\u00e9t\u00e9","T\u00e9moignages"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.legalife.fr\/guides-juridiques\/elles-ont-redige-leurs-statuts-de-sas-sur-legalife\/#respond"]}]},{"@type":"Person","@id":"https:\/\/www.legalife.fr\/guides-juridiques\/#\/schema\/person\/a8d0c9e67c195e2bb19533e49a8b0c3d","name":"Thomas Rivoire","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.legalife.fr\/guides-juridiques\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1ba73b56954b9b86c6fd31776e8ad00a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1ba73b56954b9b86c6fd31776e8ad00a?s=96&d=mm&r=g","caption":"Thomas Rivoire"},"description":"Dipl\u00f4m\u00e9 d'HEC Paris et titulaire du dipl\u00f4me sup\u00e9rieur du notariat, j'ai plus de cinq ann\u00e9es d'exp\u00e9rience au sein d'une \u00e9tude de notaires. En tant que co-fondateur de LegaLife, je suis en charge du contenu juridique et du d\u00e9veloppement de l'offre de services que nous proposons \u00e0 nos clients.","sameAs":["https:\/\/fr.linkedin.com\/in\/rivoirethomas"],"url":"https:\/\/www.legalife.fr\/guides-juridiques\/author\/thomas\/"}]}},"_links":{"self":[{"href":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-json\/wp\/v2\/posts\/579"}],"collection":[{"href":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-json\/wp\/v2\/comments?post=579"}],"version-history":[{"count":46,"href":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-json\/wp\/v2\/posts\/579\/revisions"}],"predecessor-version":[{"id":6480,"href":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-json\/wp\/v2\/posts\/579\/revisions\/6480"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-json\/wp\/v2\/media\/610"}],"wp:attachment":[{"href":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-json\/wp\/v2\/media?parent=579"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-json\/wp\/v2\/categories?post=579"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-json\/wp\/v2\/tags?post=579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}