{"id":523,"date":"2013-11-25T14:45:04","date_gmt":"2013-11-25T13:45:04","guid":{"rendered":"http:\/\/www.legalife.fr\/blog\/?p=523"},"modified":"2018-11-27T12:10:21","modified_gmt":"2018-11-27T11:10:21","slug":"resiliation-de-bail","status":"publish","type":"post","link":"https:\/\/www.legalife.fr\/guides-juridiques\/resiliation-de-bail\/","title":{"rendered":"Quand et comment r\u00e9silier votre contrat de bail ?"},"content":{"rendered":"<p style=\"text-align: justify;\">Vous souhaitez quitter prochainement votre logement ? Pour donner valablement cong\u00e9 \u00e0 votre propri\u00e9taire vous devrez toujours effectuer une r\u00e9siliation de bail. A la diff\u00e9rence du propri\u00e9taire assujetti \u00e0 une l\u00e9gislation contraignante, le locataire b\u00e9n\u00e9ficie g\u00e9n\u00e9ralement de r\u00e8gles assouplies dans le cas d&#8217;une location \u00e0 titre de r\u00e9sidence principale. Les locations de logements nus \u00e0 usage d&#8217;habitation sont r\u00e9gies par la loi du 6 juillet 1989. Elle fixe de mani\u00e8re pr\u00e9cise les conditions de r\u00e9siliation de bail.<\/p>\n<div id=\"toc_container\" class=\"no_bullets\"><p class=\"toc_title\">Table des mati&egrave;res<\/p><ul class=\"toc_list\"><li><a href=\"#Pour_quitter_votre_logement_respectez_certaines_formalites\"><span class=\"toc_number toc_depth_1\">1<\/span> Pour quitter votre logement, respectez certaines formalit\u00e9s<\/a><ul><li><ul><li><a href=\"#La_notification_au_proprietaire_de_la_resiliation_du_bail\"><span class=\"toc_number toc_depth_3\">1.0.1<\/span> La notification au propri\u00e9taire de la r\u00e9siliation du bail<\/a><\/li><li><a href=\"#Le_respect_de_la_periode_de_preavis\"><span class=\"toc_number toc_depth_3\">1.0.2<\/span> Le respect de la p\u00e9riode de pr\u00e9avis<\/a><\/li><\/ul><\/li><\/ul><\/li><li><a href=\"#Quand_et_comment_rediger_la_lettre_de_resiliation_de_bail\"><span class=\"toc_number toc_depth_1\">2<\/span> Quand et comment r\u00e9diger la lettre de r\u00e9siliation de bail ?<\/a><\/li><li><a href=\"#Le_logement_loue_n8217est_pas_votre_residence_principale\"><span class=\"toc_number toc_depth_1\">3<\/span> Le logement lou\u00e9 n&#8217;est pas votre r\u00e9sidence principale<\/a><\/li><\/ul><\/div>\n<h2 style=\"text-align: justify;\"><span id=\"Pour_quitter_votre_logement_respectez_certaines_formalites\">Pour quitter votre logement, respectez certaines formalit\u00e9s<\/span><\/h2>\n<h4 style=\"text-align: justify;\"><span id=\"La_notification_au_proprietaire_de_la_resiliation_du_bail\">La notification au propri\u00e9taire de la r\u00e9siliation du bail<\/span><\/h4>\n<p style=\"text-align: justify;\">Vous devrez informer votre propri\u00e9taire de fa\u00e7on formelle et ne pas vous limiter \u00e0 une information orale par t\u00e9l\u00e9phone ou de vive voix. Vous avez pour cela 2 possibilit\u00e9s, la lettre recommand\u00e9e avec accus\u00e9 de r\u00e9ception ou l&#8217;acte d&#8217;huissier. Le mode de r\u00e9siliation de bail doit \u00eatre pr\u00e9cis\u00e9 dans le contrat.<\/p>\n<p style=\"text-align: justify;\">Vous ne pouvez pas donner cong\u00e9 par lettre simple ou en utilisant les outils tels que t\u00e9l\u00e9copie, internet ou SMS. La remise des cl\u00e9s au concierge ne peut \u00e9galement tenir lieu de cong\u00e9.<\/p>\n<p style=\"text-align: justify;\">Lorsqu&#8217;il existe plusieurs titulaires-signataires du bail, la notification doit \u00eatre sign\u00e9e par tous les co-titulaires. Si le logement appartient \u00e0 plusieurs propri\u00e9taires, tous signataires du bail, vous devrez \u00e9galement envoyer \u00e0 chacun un exemplaire du courrier.<\/p>\n<h4 style=\"text-align: justify;\"><span id=\"Le_respect_de_la_periode_de_preavis\">Le respect de la p\u00e9riode de pr\u00e9avis<\/span><\/h4>\n<p style=\"text-align: justify;\">Pour quitter votre logement l\u00e9galement, vous devrez donner cong\u00e9 \u00e0 votre propri\u00e9taire en respectant une p\u00e9riode dite &#8220;de pr\u00e9avis&#8221; de 3 mois pour un logement non-meubl\u00e9 et de 1 mois pour un logement meubl\u00e9. Le d\u00e9lai exig\u00e9 par la loi se calcule de jour \u00e0 jour \u00e0 partir de la date de signature de l&#8217;accus\u00e9 de r\u00e9ception du courrier recommand\u00e9 par le propri\u00e9taire ou de la date de l&#8217;acte d&#8217;huissier. Cependant ce d\u00e9lai peut \u00eatre r\u00e9duit dans certains cas bien particuliers comme :<\/p>\n<ul>\n<li>une mutation professionnelle ;<\/li>\n<li>la perte d&#8217;un emploi ou l&#8217;obtention d&#8217;un premier ou nouvel emploi apr\u00e8s un licenciement ;<\/li>\n<li>des raisons de sant\u00e9 pour les locataires de plus de 70 ans ;<\/li>\n<li>les locataires b\u00e9n\u00e9ficiaires du RSA.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Si vous \u00eates concern\u00e9 par une r\u00e9duction de pr\u00e9avis. Vous devrez le pr\u00e9ciser au propri\u00e9taire en lui fournissant les justificatifs correspondant au motif que vous invoquerez. Dans le cas contraire, vous devrez respecter le d\u00e9lai mais n&#8217;aurez aucune explication \u00e0 fournir pour votre d\u00e9part.<\/p>\n<h2 style=\"text-align: justify;\"><span id=\"Quand_et_comment_rediger_la_lettre_de_resiliation_de_bail\">Quand et comment r\u00e9diger la lettre de r\u00e9siliation de bail ?<\/span><\/h2>\n<p style=\"text-align: justify;\">La lettre, adress\u00e9e en recommand\u00e9 avec accus\u00e9 de r\u00e9ception, doit mentionner la date, vos noms et adresses et le destinataire. N&#8217;oubliez pas de notifier les \u00e9ventuelles pi\u00e8ces jointes.<\/p>\n<h2 style=\"text-align: justify;\"><span id=\"Le_logement_loue_n8217est_pas_votre_residence_principale\">Le logement lou\u00e9 n&#8217;est pas votre r\u00e9sidence principale<\/span><\/h2>\n<p style=\"text-align: justify;\">Si votre logement est lou\u00e9 et utilis\u00e9 \u00e0 titre de r\u00e9sidence secondaire ou de location de vacances, le cong\u00e9 n&#8217;est pas li\u00e9 \u00e0 des r\u00e8gles imp\u00e9ratives. Dans ce cas, seules les clauses mentionn\u00e9es dans le contrat tiendront lieu d&#8217;obligation. Relisez bien votre contrat car dans le cas d&#8217;une location de courte dur\u00e9e ou saisonni\u00e8re, vous risquez de devoir r\u00e9gler loyers et charges jusqu&#8217;\u00e0 l&#8217;\u00e9ch\u00e9ance du bail.<\/p>\n\n<div class=\"kk-star-ratings\n     kksr-valign-bottom     kksr-align-left    \"\n    data-payload=\"{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;523&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;count&quot;:&quot;4&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;5&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;5\\\/5 - (4 votes)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;width&quot;:&quot;142.5&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;}\">\n    \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 142.5px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n    \n<div class=\"kksr-legend\">\n            5\/5 - (4 votes)    <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Vous souhaitez quitter votre logement ? Pour donner valablement cong\u00e9 \u00e0 votre propri\u00e9taire vous devrez toujours effectuer une r\u00e9siliation de bail.<\/p>\n","protected":false},"author":3,"featured_media":522,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[407],"tags":[33,32],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Quand et comment r\u00e9silier votre contrat de bail ? - LegaLife<\/title>\n<meta name=\"description\" content=\"Vous souhaitez quitter votre logement ? Pour donner valablement cong\u00e9 \u00e0 votre propri\u00e9taire vous devrez toujours effectuer une r\u00e9siliation de bail.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.legalife.fr\/guides-juridiques\/resiliation-de-bail\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quand et comment r\u00e9silier votre contrat de bail ? - LegaLife\" \/>\n<meta property=\"og:description\" content=\"Vous souhaitez quitter votre logement ? Pour donner valablement cong\u00e9 \u00e0 votre propri\u00e9taire vous devrez toujours effectuer une r\u00e9siliation de bail.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.legalife.fr\/guides-juridiques\/resiliation-de-bail\/\" \/>\n<meta property=\"og:site_name\" content=\"LegaLife\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/legalife.fr\" \/>\n<meta property=\"article:published_time\" content=\"2013-11-25T13:45:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-11-27T11:10:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/d1mxkq1wocxjoy.cloudfront.net\/guides-uploads\/2013\/11\/22230623\/R%C3%A9siliation-de-bail.png\" \/>\n\t<meta property=\"og:image:width\" content=\"680\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Thomas Rivoire\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/#organization\",\"name\":\"LegaLife\",\"url\":\"https:\/\/www.legalife.fr\/guides-juridiques\/\",\"sameAs\":[\"https:\/\/instagram.com\/lega_life\/\",\"https:\/\/www.linkedin.com\/company\/legalife\",\"https:\/\/www.pinterest.com\/Legalife_fr\/\",\"https:\/\/www.youtube.com\/channel\/UCB5gtPHHwPuKr7yHnd78f1g\",\"https:\/\/www.facebook.com\/legalife.fr\",\"https:\/\/twitter.com\/legalife\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.legalife.fr\/guides-juridiques\/wp-content\/uploads\/2016\/06\/versionslogo-01.png\",\"contentUrl\":\"https:\/\/www.legalife.fr\/guides-juridiques\/wp-content\/uploads\/2016\/06\/versionslogo-01.png\",\"width\":2292,\"height\":625,\"caption\":\"LegaLife\"},\"image\":{\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/#\/schema\/logo\/image\/\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/#website\",\"url\":\"https:\/\/www.legalife.fr\/guides-juridiques\/\",\"name\":\"LegaLife\",\"description\":\"Toute l&#039;actualit\u00e9 juridique\",\"publisher\":{\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.legalife.fr\/guides-juridiques\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/resiliation-de-bail\/#primaryimage\",\"url\":\"https:\/\/d1mxkq1wocxjoy.cloudfront.net\/guides-uploads\/2013\/11\/22230623\/R%C3%A9siliation-de-bail.png\",\"contentUrl\":\"https:\/\/d1mxkq1wocxjoy.cloudfront.net\/guides-uploads\/2013\/11\/22230623\/R%C3%A9siliation-de-bail.png\",\"width\":680,\"height\":450,\"caption\":\"Quand et comment r\u00e9silier votre contrat de bail ?\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/resiliation-de-bail\/#webpage\",\"url\":\"https:\/\/www.legalife.fr\/guides-juridiques\/resiliation-de-bail\/\",\"name\":\"Quand et comment r\u00e9silier votre contrat de bail ? - LegaLife\",\"isPartOf\":{\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/resiliation-de-bail\/#primaryimage\"},\"datePublished\":\"2013-11-25T13:45:04+00:00\",\"dateModified\":\"2018-11-27T11:10:21+00:00\",\"description\":\"Vous souhaitez quitter votre logement ? Pour donner valablement cong\u00e9 \u00e0 votre propri\u00e9taire vous devrez toujours effectuer une r\u00e9siliation de bail.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/resiliation-de-bail\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.legalife.fr\/guides-juridiques\/resiliation-de-bail\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/resiliation-de-bail\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Guides juridiques\",\"item\":\"https:\/\/www.legalife.fr\/guides-juridiques\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Immobilier\",\"item\":\"https:\/\/www.legalife.fr\/guides-juridiques\/immobilier\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Louer un logement\",\"item\":\"https:\/\/www.legalife.fr\/guides-juridiques\/immobilier\/louer-un-logement\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Quand et comment r\u00e9silier votre contrat de bail ?\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/resiliation-de-bail\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/resiliation-de-bail\/#webpage\"},\"author\":{\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/#\/schema\/person\/a8d0c9e67c195e2bb19533e49a8b0c3d\"},\"headline\":\"Quand et comment r\u00e9silier votre contrat de bail ?\",\"datePublished\":\"2013-11-25T13:45:04+00:00\",\"dateModified\":\"2018-11-27T11:10:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/resiliation-de-bail\/#webpage\"},\"wordCount\":548,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/resiliation-de-bail\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/d1mxkq1wocxjoy.cloudfront.net\/guides-uploads\/2013\/11\/22230623\/R%C3%A9siliation-de-bail.png\",\"keywords\":[\"baux ; contrat de bail ; r\u00e9siliation contrat de bail ; r\u00e9siliation de bail ; r\u00e9siliation d'un bail\",\"R\u00e9siliation ; bail\"],\"articleSection\":[\"Louer un logement\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.legalife.fr\/guides-juridiques\/resiliation-de-bail\/#respond\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/#\/schema\/person\/a8d0c9e67c195e2bb19533e49a8b0c3d\",\"name\":\"Thomas Rivoire\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1ba73b56954b9b86c6fd31776e8ad00a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1ba73b56954b9b86c6fd31776e8ad00a?s=96&d=mm&r=g\",\"caption\":\"Thomas Rivoire\"},\"description\":\"Dipl\u00f4m\u00e9 d'HEC Paris et titulaire du dipl\u00f4me sup\u00e9rieur du notariat, j'ai plus de cinq ann\u00e9es d'exp\u00e9rience au sein d'une \u00e9tude de notaires. En tant que co-fondateur de LegaLife, je suis en charge du contenu juridique et du d\u00e9veloppement de l'offre de services que nous proposons \u00e0 nos clients.\",\"sameAs\":[\"https:\/\/fr.linkedin.com\/in\/rivoirethomas\"],\"url\":\"https:\/\/www.legalife.fr\/guides-juridiques\/author\/thomas\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quand et comment r\u00e9silier votre contrat de bail ? - LegaLife","description":"Vous souhaitez quitter votre logement ? Pour donner valablement cong\u00e9 \u00e0 votre propri\u00e9taire vous devrez toujours effectuer une r\u00e9siliation de bail.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.legalife.fr\/guides-juridiques\/resiliation-de-bail\/","og_locale":"fr_FR","og_type":"article","og_title":"Quand et comment r\u00e9silier votre contrat de bail ? - LegaLife","og_description":"Vous souhaitez quitter votre logement ? Pour donner valablement cong\u00e9 \u00e0 votre propri\u00e9taire vous devrez toujours effectuer une r\u00e9siliation de bail.","og_url":"https:\/\/www.legalife.fr\/guides-juridiques\/resiliation-de-bail\/","og_site_name":"LegaLife","article_publisher":"https:\/\/www.facebook.com\/legalife.fr","article_published_time":"2013-11-25T13:45:04+00:00","article_modified_time":"2018-11-27T11:10:21+00:00","og_image":[{"width":680,"height":450,"url":"https:\/\/d1mxkq1wocxjoy.cloudfront.net\/guides-uploads\/2013\/11\/22230623\/R%C3%A9siliation-de-bail.png","type":"image\/png"}],"twitter_misc":{"Written by":"Thomas Rivoire","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/www.legalife.fr\/guides-juridiques\/#organization","name":"LegaLife","url":"https:\/\/www.legalife.fr\/guides-juridiques\/","sameAs":["https:\/\/instagram.com\/lega_life\/","https:\/\/www.linkedin.com\/company\/legalife","https:\/\/www.pinterest.com\/Legalife_fr\/","https:\/\/www.youtube.com\/channel\/UCB5gtPHHwPuKr7yHnd78f1g","https:\/\/www.facebook.com\/legalife.fr","https:\/\/twitter.com\/legalife"],"logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.legalife.fr\/guides-juridiques\/#\/schema\/logo\/image\/","url":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-content\/uploads\/2016\/06\/versionslogo-01.png","contentUrl":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-content\/uploads\/2016\/06\/versionslogo-01.png","width":2292,"height":625,"caption":"LegaLife"},"image":{"@id":"https:\/\/www.legalife.fr\/guides-juridiques\/#\/schema\/logo\/image\/"}},{"@type":"WebSite","@id":"https:\/\/www.legalife.fr\/guides-juridiques\/#website","url":"https:\/\/www.legalife.fr\/guides-juridiques\/","name":"LegaLife","description":"Toute l&#039;actualit\u00e9 juridique","publisher":{"@id":"https:\/\/www.legalife.fr\/guides-juridiques\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.legalife.fr\/guides-juridiques\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.legalife.fr\/guides-juridiques\/resiliation-de-bail\/#primaryimage","url":"https:\/\/d1mxkq1wocxjoy.cloudfront.net\/guides-uploads\/2013\/11\/22230623\/R%C3%A9siliation-de-bail.png","contentUrl":"https:\/\/d1mxkq1wocxjoy.cloudfront.net\/guides-uploads\/2013\/11\/22230623\/R%C3%A9siliation-de-bail.png","width":680,"height":450,"caption":"Quand et comment r\u00e9silier votre contrat de bail ?"},{"@type":"WebPage","@id":"https:\/\/www.legalife.fr\/guides-juridiques\/resiliation-de-bail\/#webpage","url":"https:\/\/www.legalife.fr\/guides-juridiques\/resiliation-de-bail\/","name":"Quand et comment r\u00e9silier votre contrat de bail ? - LegaLife","isPartOf":{"@id":"https:\/\/www.legalife.fr\/guides-juridiques\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.legalife.fr\/guides-juridiques\/resiliation-de-bail\/#primaryimage"},"datePublished":"2013-11-25T13:45:04+00:00","dateModified":"2018-11-27T11:10:21+00:00","description":"Vous souhaitez quitter votre logement ? Pour donner valablement cong\u00e9 \u00e0 votre propri\u00e9taire vous devrez toujours effectuer une r\u00e9siliation de bail.","breadcrumb":{"@id":"https:\/\/www.legalife.fr\/guides-juridiques\/resiliation-de-bail\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.legalife.fr\/guides-juridiques\/resiliation-de-bail\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.legalife.fr\/guides-juridiques\/resiliation-de-bail\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Guides juridiques","item":"https:\/\/www.legalife.fr\/guides-juridiques\/"},{"@type":"ListItem","position":2,"name":"Immobilier","item":"https:\/\/www.legalife.fr\/guides-juridiques\/immobilier\/"},{"@type":"ListItem","position":3,"name":"Louer un logement","item":"https:\/\/www.legalife.fr\/guides-juridiques\/immobilier\/louer-un-logement\/"},{"@type":"ListItem","position":4,"name":"Quand et comment r\u00e9silier votre contrat de bail ?"}]},{"@type":"Article","@id":"https:\/\/www.legalife.fr\/guides-juridiques\/resiliation-de-bail\/#article","isPartOf":{"@id":"https:\/\/www.legalife.fr\/guides-juridiques\/resiliation-de-bail\/#webpage"},"author":{"@id":"https:\/\/www.legalife.fr\/guides-juridiques\/#\/schema\/person\/a8d0c9e67c195e2bb19533e49a8b0c3d"},"headline":"Quand et comment r\u00e9silier votre contrat de bail ?","datePublished":"2013-11-25T13:45:04+00:00","dateModified":"2018-11-27T11:10:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.legalife.fr\/guides-juridiques\/resiliation-de-bail\/#webpage"},"wordCount":548,"commentCount":1,"publisher":{"@id":"https:\/\/www.legalife.fr\/guides-juridiques\/#organization"},"image":{"@id":"https:\/\/www.legalife.fr\/guides-juridiques\/resiliation-de-bail\/#primaryimage"},"thumbnailUrl":"https:\/\/d1mxkq1wocxjoy.cloudfront.net\/guides-uploads\/2013\/11\/22230623\/R%C3%A9siliation-de-bail.png","keywords":["baux ; contrat de bail ; r\u00e9siliation contrat de bail ; r\u00e9siliation de bail ; r\u00e9siliation d'un bail","R\u00e9siliation ; bail"],"articleSection":["Louer un logement"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.legalife.fr\/guides-juridiques\/resiliation-de-bail\/#respond"]}]},{"@type":"Person","@id":"https:\/\/www.legalife.fr\/guides-juridiques\/#\/schema\/person\/a8d0c9e67c195e2bb19533e49a8b0c3d","name":"Thomas Rivoire","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.legalife.fr\/guides-juridiques\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1ba73b56954b9b86c6fd31776e8ad00a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1ba73b56954b9b86c6fd31776e8ad00a?s=96&d=mm&r=g","caption":"Thomas Rivoire"},"description":"Dipl\u00f4m\u00e9 d'HEC Paris et titulaire du dipl\u00f4me sup\u00e9rieur du notariat, j'ai plus de cinq ann\u00e9es d'exp\u00e9rience au sein d'une \u00e9tude de notaires. En tant que co-fondateur de LegaLife, je suis en charge du contenu juridique et du d\u00e9veloppement de l'offre de services que nous proposons \u00e0 nos clients.","sameAs":["https:\/\/fr.linkedin.com\/in\/rivoirethomas"],"url":"https:\/\/www.legalife.fr\/guides-juridiques\/author\/thomas\/"}]}},"_links":{"self":[{"href":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-json\/wp\/v2\/posts\/523"}],"collection":[{"href":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-json\/wp\/v2\/comments?post=523"}],"version-history":[{"count":16,"href":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-json\/wp\/v2\/posts\/523\/revisions"}],"predecessor-version":[{"id":10849,"href":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-json\/wp\/v2\/posts\/523\/revisions\/10849"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-json\/wp\/v2\/media\/522"}],"wp:attachment":[{"href":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-json\/wp\/v2\/media?parent=523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-json\/wp\/v2\/categories?post=523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-json\/wp\/v2\/tags?post=523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}