{"id":4998,"date":"2015-11-24T12:26:17","date_gmt":"2015-11-24T11:26:17","guid":{"rendered":"https:\/\/www.legalife.fr\/blog\/?p=4998"},"modified":"2016-12-20T18:01:12","modified_gmt":"2016-12-20T17:01:12","slug":"comment-trouver-un-locataire","status":"publish","type":"post","link":"https:\/\/www.legalife.fr\/guides-juridiques\/comment-trouver-un-locataire\/","title":{"rendered":"Comment trouver un locataire ?"},"content":{"rendered":"<p>Avant de conclure un <a href=\"https:\/\/www.legalife.fr\/modele\/bail-d-habitation-meublee\/\">bail d&#8217;habitation<\/a> pour louer son bien, l&#8217;\u00e9ternelle question est celle de la recherche du locataire parfait. Alors, comment trouver un locataire qui r\u00e9ponde \u00e0 ses crit\u00e8res ?<\/p>\n<h2>Trouver un locataire : la recherche du locataire id\u00e9al<\/h2>\n<p class=\"row baseline--default\">Pour trouver un locataire, vous avez deux possibilit\u00e9s :<\/p>\n<ul class=\"classic-list row\">\n<li class=\"baseline--default\"><strong>Trouver un\u00a0locataire par vous m\u00eame\u00a0<\/strong><\/li>\n<\/ul>\n<p>Vous pouvez ainsi publier une annonce sur des sites sp\u00e9cialis\u00e9s (par exemple : leboncoin, seloger, etc.). Mais vous pouvez \u00e9galement faire circuler cette annonce sur les r\u00e9seaux sociaux ou\u00a0demander \u00e0 votre entourage.<\/p>\n<p><u>Avantage\u00a0<\/u>: vous ne payez donc pas de frais d&#8217;agence lors de la conclusion du bail.<br \/>\n<u>Inconv\u00e9nient :<\/u> trouver un locataire sans avoir recours \u00e0 un professionnel prend du temps et demande ainsi d&#8217;\u00eatre disponible pour les visites du bien immobilier.<\/p>\n<ul class=\"classic-list row\">\n<li class=\"baseline--default\"><strong>Passer par une agence immobili\u00e8re\u00a0<\/strong><\/li>\n<\/ul>\n<p>Vous pouvez signer un <a href=\"https:\/\/www.legalife.fr\/modele\/mandat-de-gestion-locative\/\">mandat de gestion \u00a0locative<\/a> avec une agence immobili\u00e8re qui se chargera de trouver un locataire pour vous.<\/p>\n<p><u>Avantage\u00a0<\/u>: vous d\u00e9l\u00e9guez alors la recherche du locataire \u00e0 un professionnel du secteur. Il s&#8217;occupe ainsi\u00a0des visites du bien immobilier.<br \/>\n<u>Inconv\u00e9nient :<\/u>\u00a0les frais d&#8217;agence sont parfois \u00e9lev\u00e9s. V\u00e9rifiez donc bien leur montant avant de vous engager.<\/p>\n<h2>Limiter les risques d&#8217;impay\u00e9s en demandant des justificatifs<\/h2>\n<p class=\"row baseline--default\">Afin de limiter les risques d&#8217;impay\u00e9s, il convient ensuite de prendre des pr\u00e9cautions.<\/p>\n<p>En effet, un locataire qui ne paie pas son loyer peut avoir des cons\u00e9quences graves sur votre sant\u00e9 financi\u00e8re, notamment si vous comptez sur le loyer pour rembourser l&#8217;emprunt qui vous a servi \u00e0 acqu\u00e9rir le bien immobilier lou\u00e9.<\/p>\n<p>Pour minimiser le risque d&#8217;impay\u00e9, assurez-vous donc que le potentiel locataire ait des revenus suffisants pour payer chaque mois le loyer demand\u00e9.<\/p>\n<p>Vous pouvez lui demander de vous fournir les documents suivants\u00a0:<\/p>\n<ul class=\"classic-list row\">\n<li class=\"row baseline--default\">Fiches de paie,<\/li>\n<li class=\"row baseline--default\">Dernier avis d&#8217;imposition.<\/li>\n<\/ul>\n<p class=\"row baseline--default\">En compl\u00e9ment, si les revenus semblent insuffisants, imposez au locataire de vous fournir une caution. Un tiers se porte alors caution du locataire, et si le locataire ne paie pas, la caution paiera le loyer \u00e0 sa place.<\/p>\n<p class=\"row baseline--default\">Le bailleur n&#8217;a toutefois pas le droit de demander au locataire de lui fournir une caution si il a souscrit en amont une assurance relative aux risques locatifs.<\/p>\n<p>Une fois votre locataire id\u00e9al trouv\u00e9, vous pourrez alors signer un <a href=\"https:\/\/www.legalife.fr\/modele\/bail-d-habitation-meublee\/\">bail d&#8217;habitation meubl\u00e9e<\/a> ou <a href=\"https:\/\/www.legalife.fr\/modele\/bail-d-habitation-non-meublee\/\">non meubl\u00e9e<\/a> pour commencer la location.<\/p>\n\n<div class=\"kk-star-ratings\n     kksr-valign-bottom     kksr-align-left    \"\n    data-payload=\"{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;4998&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;count&quot;:&quot;4&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;5&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;5\\\/5 - (4 votes)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;width&quot;:&quot;142.5&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;}\">\n    \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 142.5px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n    \n<div class=\"kksr-legend\">\n            5\/5 - (4 votes)    <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Avant de conclure un bail d&#8217;habitation pour louer son bien, l&#8217;\u00e9ternelle question est celle de la recherche du locataire parfait. Alors, comment trouver un locataire qui r\u00e9ponde \u00e0 ses crit\u00e8res ? Trouver un locataire : la recherche du locataire id\u00e9al Pour trouver un locataire, vous avez deux possibilit\u00e9s : Trouver un\u00a0locataire par vous m\u00eame\u00a0 Vous [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5001,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[407],"tags":[254],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Comment trouver un locataire ? - LegaLife<\/title>\n<meta name=\"description\" content=\"Vous \u00eates propri\u00e9taire d&#039;un bien immobilier \u00e0 usage d&#039;habitation\u00a0et\u00a0vous souhaitez\u00a0le louer ? Comment faire pour trouver un locataire qui vous convienne ?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.legalife.fr\/guides-juridiques\/comment-trouver-un-locataire\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comment trouver un locataire ? - LegaLife\" \/>\n<meta property=\"og:description\" content=\"Vous \u00eates propri\u00e9taire d&#039;un bien immobilier \u00e0 usage d&#039;habitation\u00a0et\u00a0vous souhaitez\u00a0le louer ? Comment faire pour trouver un locataire qui vous convienne ?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.legalife.fr\/guides-juridiques\/comment-trouver-un-locataire\/\" \/>\n<meta property=\"og:site_name\" content=\"LegaLife\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/legalife.fr\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/legalife.fr\" \/>\n<meta property=\"article:published_time\" content=\"2015-11-24T11:26:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-12-20T17:01:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/d1mxkq1wocxjoy.cloudfront.net\/guides-uploads\/2015\/11\/22230104\/comment-trouver-un-locataire-1024x683.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"LegaLife\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/#organization\",\"name\":\"LegaLife\",\"url\":\"https:\/\/www.legalife.fr\/guides-juridiques\/\",\"sameAs\":[\"https:\/\/instagram.com\/lega_life\/\",\"https:\/\/www.linkedin.com\/company\/legalife\",\"https:\/\/www.pinterest.com\/Legalife_fr\/\",\"https:\/\/www.youtube.com\/channel\/UCB5gtPHHwPuKr7yHnd78f1g\",\"https:\/\/www.facebook.com\/legalife.fr\",\"https:\/\/twitter.com\/legalife\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.legalife.fr\/guides-juridiques\/wp-content\/uploads\/2016\/06\/versionslogo-01.png\",\"contentUrl\":\"https:\/\/www.legalife.fr\/guides-juridiques\/wp-content\/uploads\/2016\/06\/versionslogo-01.png\",\"width\":2292,\"height\":625,\"caption\":\"LegaLife\"},\"image\":{\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/#\/schema\/logo\/image\/\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/#website\",\"url\":\"https:\/\/www.legalife.fr\/guides-juridiques\/\",\"name\":\"LegaLife\",\"description\":\"Toute l&#039;actualit\u00e9 juridique\",\"publisher\":{\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.legalife.fr\/guides-juridiques\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/comment-trouver-un-locataire\/#primaryimage\",\"url\":\"https:\/\/d1mxkq1wocxjoy.cloudfront.net\/guides-uploads\/2015\/11\/22230104\/comment-trouver-un-locataire.jpg\",\"contentUrl\":\"https:\/\/d1mxkq1wocxjoy.cloudfront.net\/guides-uploads\/2015\/11\/22230104\/comment-trouver-un-locataire.jpg\",\"width\":5472,\"height\":3648,\"caption\":\"comment trouver un locataire\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/comment-trouver-un-locataire\/#webpage\",\"url\":\"https:\/\/www.legalife.fr\/guides-juridiques\/comment-trouver-un-locataire\/\",\"name\":\"Comment trouver un locataire ? - LegaLife\",\"isPartOf\":{\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/comment-trouver-un-locataire\/#primaryimage\"},\"datePublished\":\"2015-11-24T11:26:17+00:00\",\"dateModified\":\"2016-12-20T17:01:12+00:00\",\"description\":\"Vous \u00eates propri\u00e9taire d'un bien immobilier \u00e0 usage d'habitation\u00a0et\u00a0vous souhaitez\u00a0le louer ? Comment faire pour trouver un locataire qui vous convienne ?\",\"breadcrumb\":{\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/comment-trouver-un-locataire\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.legalife.fr\/guides-juridiques\/comment-trouver-un-locataire\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/comment-trouver-un-locataire\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Guides juridiques\",\"item\":\"https:\/\/www.legalife.fr\/guides-juridiques\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Immobilier\",\"item\":\"https:\/\/www.legalife.fr\/guides-juridiques\/immobilier\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Louer un logement\",\"item\":\"https:\/\/www.legalife.fr\/guides-juridiques\/immobilier\/louer-un-logement\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Comment trouver un locataire ?\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/comment-trouver-un-locataire\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/comment-trouver-un-locataire\/#webpage\"},\"author\":{\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/#\/schema\/person\/48a14bcb904db9d47811591521a61112\"},\"headline\":\"Comment trouver un locataire ?\",\"datePublished\":\"2015-11-24T11:26:17+00:00\",\"dateModified\":\"2016-12-20T17:01:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/comment-trouver-un-locataire\/#webpage\"},\"wordCount\":397,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/comment-trouver-un-locataire\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/d1mxkq1wocxjoy.cloudfront.net\/guides-uploads\/2015\/11\/22230104\/comment-trouver-un-locataire.jpg\",\"keywords\":[\"immobilier\"],\"articleSection\":[\"Louer un logement\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.legalife.fr\/guides-juridiques\/comment-trouver-un-locataire\/#respond\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/#\/schema\/person\/48a14bcb904db9d47811591521a61112\",\"name\":\"LegaLife\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.legalife.fr\/guides-juridiques\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0c59f9bc966559d7cf8640cbb8b89f68?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0c59f9bc966559d7cf8640cbb8b89f68?s=96&d=mm&r=g\",\"caption\":\"LegaLife\"},\"description\":\"LegaLife est un site proposant un accompagnement juridique simple et accessible aux TPE\/PME et aux particuliers. Cette solution permet \u00e0 nos membres de gagner du temps et d'\u00e9conomiser de l'argent face \u00e0 leurs probl\u00e9matiques juridiques.\",\"sameAs\":[\"http:\/\/www.legalife.fr\",\"https:\/\/www.facebook.com\/legalife.fr\",\"https:\/\/www.linkedin.com\/company\/legalife\",\"https:\/\/www.pinterest.com\/Legalife_fr\/\",\"https:\/\/twitter.com\/https:\/\/twitter.com\/legalife\"],\"url\":\"https:\/\/www.legalife.fr\/guides-juridiques\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comment trouver un locataire ? - LegaLife","description":"Vous \u00eates propri\u00e9taire d'un bien immobilier \u00e0 usage d'habitation\u00a0et\u00a0vous souhaitez\u00a0le louer ? Comment faire pour trouver un locataire qui vous convienne ?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.legalife.fr\/guides-juridiques\/comment-trouver-un-locataire\/","og_locale":"fr_FR","og_type":"article","og_title":"Comment trouver un locataire ? - LegaLife","og_description":"Vous \u00eates propri\u00e9taire d'un bien immobilier \u00e0 usage d'habitation\u00a0et\u00a0vous souhaitez\u00a0le louer ? Comment faire pour trouver un locataire qui vous convienne ?","og_url":"https:\/\/www.legalife.fr\/guides-juridiques\/comment-trouver-un-locataire\/","og_site_name":"LegaLife","article_publisher":"https:\/\/www.facebook.com\/legalife.fr","article_author":"https:\/\/www.facebook.com\/legalife.fr","article_published_time":"2015-11-24T11:26:17+00:00","article_modified_time":"2016-12-20T17:01:12+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/d1mxkq1wocxjoy.cloudfront.net\/guides-uploads\/2015\/11\/22230104\/comment-trouver-un-locataire-1024x683.jpg","type":"image\/jpeg"}],"twitter_misc":{"Written by":"LegaLife","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/www.legalife.fr\/guides-juridiques\/#organization","name":"LegaLife","url":"https:\/\/www.legalife.fr\/guides-juridiques\/","sameAs":["https:\/\/instagram.com\/lega_life\/","https:\/\/www.linkedin.com\/company\/legalife","https:\/\/www.pinterest.com\/Legalife_fr\/","https:\/\/www.youtube.com\/channel\/UCB5gtPHHwPuKr7yHnd78f1g","https:\/\/www.facebook.com\/legalife.fr","https:\/\/twitter.com\/legalife"],"logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.legalife.fr\/guides-juridiques\/#\/schema\/logo\/image\/","url":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-content\/uploads\/2016\/06\/versionslogo-01.png","contentUrl":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-content\/uploads\/2016\/06\/versionslogo-01.png","width":2292,"height":625,"caption":"LegaLife"},"image":{"@id":"https:\/\/www.legalife.fr\/guides-juridiques\/#\/schema\/logo\/image\/"}},{"@type":"WebSite","@id":"https:\/\/www.legalife.fr\/guides-juridiques\/#website","url":"https:\/\/www.legalife.fr\/guides-juridiques\/","name":"LegaLife","description":"Toute l&#039;actualit\u00e9 juridique","publisher":{"@id":"https:\/\/www.legalife.fr\/guides-juridiques\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.legalife.fr\/guides-juridiques\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.legalife.fr\/guides-juridiques\/comment-trouver-un-locataire\/#primaryimage","url":"https:\/\/d1mxkq1wocxjoy.cloudfront.net\/guides-uploads\/2015\/11\/22230104\/comment-trouver-un-locataire.jpg","contentUrl":"https:\/\/d1mxkq1wocxjoy.cloudfront.net\/guides-uploads\/2015\/11\/22230104\/comment-trouver-un-locataire.jpg","width":5472,"height":3648,"caption":"comment trouver un locataire"},{"@type":"WebPage","@id":"https:\/\/www.legalife.fr\/guides-juridiques\/comment-trouver-un-locataire\/#webpage","url":"https:\/\/www.legalife.fr\/guides-juridiques\/comment-trouver-un-locataire\/","name":"Comment trouver un locataire ? - LegaLife","isPartOf":{"@id":"https:\/\/www.legalife.fr\/guides-juridiques\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.legalife.fr\/guides-juridiques\/comment-trouver-un-locataire\/#primaryimage"},"datePublished":"2015-11-24T11:26:17+00:00","dateModified":"2016-12-20T17:01:12+00:00","description":"Vous \u00eates propri\u00e9taire d'un bien immobilier \u00e0 usage d'habitation\u00a0et\u00a0vous souhaitez\u00a0le louer ? Comment faire pour trouver un locataire qui vous convienne ?","breadcrumb":{"@id":"https:\/\/www.legalife.fr\/guides-juridiques\/comment-trouver-un-locataire\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.legalife.fr\/guides-juridiques\/comment-trouver-un-locataire\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.legalife.fr\/guides-juridiques\/comment-trouver-un-locataire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Guides juridiques","item":"https:\/\/www.legalife.fr\/guides-juridiques\/"},{"@type":"ListItem","position":2,"name":"Immobilier","item":"https:\/\/www.legalife.fr\/guides-juridiques\/immobilier\/"},{"@type":"ListItem","position":3,"name":"Louer un logement","item":"https:\/\/www.legalife.fr\/guides-juridiques\/immobilier\/louer-un-logement\/"},{"@type":"ListItem","position":4,"name":"Comment trouver un locataire ?"}]},{"@type":"Article","@id":"https:\/\/www.legalife.fr\/guides-juridiques\/comment-trouver-un-locataire\/#article","isPartOf":{"@id":"https:\/\/www.legalife.fr\/guides-juridiques\/comment-trouver-un-locataire\/#webpage"},"author":{"@id":"https:\/\/www.legalife.fr\/guides-juridiques\/#\/schema\/person\/48a14bcb904db9d47811591521a61112"},"headline":"Comment trouver un locataire ?","datePublished":"2015-11-24T11:26:17+00:00","dateModified":"2016-12-20T17:01:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.legalife.fr\/guides-juridiques\/comment-trouver-un-locataire\/#webpage"},"wordCount":397,"commentCount":0,"publisher":{"@id":"https:\/\/www.legalife.fr\/guides-juridiques\/#organization"},"image":{"@id":"https:\/\/www.legalife.fr\/guides-juridiques\/comment-trouver-un-locataire\/#primaryimage"},"thumbnailUrl":"https:\/\/d1mxkq1wocxjoy.cloudfront.net\/guides-uploads\/2015\/11\/22230104\/comment-trouver-un-locataire.jpg","keywords":["immobilier"],"articleSection":["Louer un logement"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.legalife.fr\/guides-juridiques\/comment-trouver-un-locataire\/#respond"]}]},{"@type":"Person","@id":"https:\/\/www.legalife.fr\/guides-juridiques\/#\/schema\/person\/48a14bcb904db9d47811591521a61112","name":"LegaLife","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.legalife.fr\/guides-juridiques\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0c59f9bc966559d7cf8640cbb8b89f68?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0c59f9bc966559d7cf8640cbb8b89f68?s=96&d=mm&r=g","caption":"LegaLife"},"description":"LegaLife est un site proposant un accompagnement juridique simple et accessible aux TPE\/PME et aux particuliers. Cette solution permet \u00e0 nos membres de gagner du temps et d'\u00e9conomiser de l'argent face \u00e0 leurs probl\u00e9matiques juridiques.","sameAs":["http:\/\/www.legalife.fr","https:\/\/www.facebook.com\/legalife.fr","https:\/\/www.linkedin.com\/company\/legalife","https:\/\/www.pinterest.com\/Legalife_fr\/","https:\/\/twitter.com\/https:\/\/twitter.com\/legalife"],"url":"https:\/\/www.legalife.fr\/guides-juridiques\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-json\/wp\/v2\/posts\/4998"}],"collection":[{"href":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-json\/wp\/v2\/comments?post=4998"}],"version-history":[{"count":5,"href":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-json\/wp\/v2\/posts\/4998\/revisions"}],"predecessor-version":[{"id":7778,"href":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-json\/wp\/v2\/posts\/4998\/revisions\/7778"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-json\/wp\/v2\/media\/5001"}],"wp:attachment":[{"href":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-json\/wp\/v2\/media?parent=4998"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-json\/wp\/v2\/categories?post=4998"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.legalife.fr\/guides-juridiques\/wp-json\/wp\/v2\/tags?post=4998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}